{"id":1357,"date":"2020-12-28T02:26:17","date_gmt":"2020-12-28T01:26:17","guid":{"rendered":"https:\/\/www.bis-sap.com\/?page_id=1357"},"modified":"2020-12-28T03:41:40","modified_gmt":"2020-12-28T02:41:40","slug":"shop1","status":"publish","type":"page","link":"https:\/\/www.bis-sap.com\/nl\/shop1\/","title":{"rendered":"SHOP1"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1357\" data-postid=\"1357\" class=\"themify_builder_content themify_builder_content-1357 themify_builder tf_clear\">\n    \t\t\t\t<!-- module_row -->\n\t\t<div  data-parallax-bg=\"desktop\" data-css_id=\"4jrv390\" data-lazy=\"1\" class=\"module_row themify_builder_row fullwidth_row_container tb_4jrv390 tb_first tf_w tf_clearfix\">\n\t\t\t\t\t<div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n\t\t\t\t\t<div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_ta19360 first\">\n\t\t\t\t\t\t\t\t\t<div class=\"tb-column-inner tf_box tf_w\">\n\t\t\t\t<!-- module text -->\n<div  class=\"module module-text tb_00ol417\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n    <h2 style=\"text-align: center;\">\u00a0<\/h2>\n<p>\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_ou5r001\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n    <div class=\"woocommerce columns-4\"><ul  class=\"loops-wrapper products classic grid4 tf_clear tf_clearfix\" data-lazy=\"1\">\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2761 status-publish first instock product_cat-bio-products product_tag-bio has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/the-chef-8x500ml\/\"><img fetchpriority=\"high\" width=\"1200\" height=\"1600\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14.jpg 1200w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14-225x300.jpg 225w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14-768x1024.jpg 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14-1152x1536.jpg 1152w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14-9x12.jpg 9w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-14-600x800.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2750 status-publish instock product_cat-bio-products has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/the-pink-chef-8x500ml\/\"><img width=\"1600\" height=\"1200\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11.jpg 1600w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11-300x225.jpg 300w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11-1024x768.jpg 1024w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11-768x576.jpg 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11-1536x1152.jpg 1536w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11-16x12.jpg 16w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-32-34-11-600x450.jpg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2740 status-publish instock product_cat-bio-products has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/organic-red-hibiscus-flowers-12x90g\/\"><img width=\"3375\" height=\"6000\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story.png 3375w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-169x300.png 169w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-576x1024.png 576w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-768x1365.png 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-864x1536.png 864w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-1152x2048.png 1152w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-7x12.png 7w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Green-and-White-with-Gold-Sticker-Photocentric-E-Commerce-Instagram-Your-Story-600x1067.png 600w\" sizes=\"(max-width: 3375px) 100vw, 3375px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2734 status-publish last instock product_cat-bio-products has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/organic-white-hibiscus-flowers-12x90g\/\"><img loading=\"lazy\" width=\"3375\" height=\"6000\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2.png 3375w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-169x300.png 169w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-576x1024.png 576w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-768x1365.png 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-864x1536.png 864w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-1152x2048.png 1152w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-7x12.png 7w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/2-600x1067.png 600w\" sizes=\"(max-width: 3375px) 100vw, 3375px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2695 status-publish first instock product_cat-bio-products has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/moussas-bissap-ginger-fever-250mlx24\/\"><img loading=\"lazy\" width=\"1200\" height=\"1600\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22.jpg 1200w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22-225x300.jpg 225w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22-768x1024.jpg 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22-1152x1536.jpg 1152w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22-9x12.jpg 9w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/06\/PHOTO-2024-06-27-19-34-22-600x800.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2599 status-publish instock product_cat-bio-products has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/ginger-fever-6x1l\/\"><img loading=\"lazy\" width=\"1709\" height=\"2560\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-scaled.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-scaled.jpg 1709w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-200x300.jpg 200w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-684x1024.jpg 684w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-768x1150.jpg 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-1025x1536.jpg 1025w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-1367x2048.jpg 1367w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-8x12.jpg 8w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-600x899.jpg 600w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2023\/07\/BissapJonathan-Ramael11-684x1024-310x464.jpg 310w\" sizes=\"(max-width: 1709px) 100vw, 1709px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2577 status-publish instock product_cat-uncategorized has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/moussas-bissap-jungle-juice-6x-1l-copy\/\"><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-scaled-300x300.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-scaled-300x300.jpg 300w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-scaled-100x100.jpg 100w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-150x150.jpg 150w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-65x65.jpg 65w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-683x1024-2000x2000.jpg 2000w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2020\/10\/347A7016-683x1024-600x600.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/div><\/li>\n<li class=\"has-post-title has-post-date has-post-category has-post-tag has-post-comment has-post-author product type-product post-2570 status-publish last instock product_cat-bio-products has-post-thumbnail purchasable product-type-simple\">\n\t<div class=\"product-image\"><a href=\"https:\/\/www.bis-sap.com\/nl\/product\/ginger-feverl-6x1l-copy\/\"><img loading=\"lazy\" width=\"1709\" height=\"2560\" src=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-scaled.jpg\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-scaled.jpg 1709w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-200x300.jpg 200w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-684x1024.jpg 684w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-768x1150.jpg 768w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-1025x1536.jpg 1025w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-1367x2048.jpg 1367w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-8x12.jpg 8w, https:\/\/www.bis-sap.com\/wp-content\/uploads\/2024\/03\/Bissap-Jonathan-Ramael-8-600x899.jpg 600w\" sizes=\"(max-width: 1709px) 100vw, 1709px\" \/><\/a><\/div><\/li>\n<\/ul>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text -->\t\t\t\t<\/div><!-- .tb-column-inner -->\n\t\t\t\t\t\t<\/div><!-- .module_column -->\n\t\t\t\t\t\t<\/div><!-- .row_inner -->\n\t\t<\/div><!-- .module_row -->\n\t\t\t\t<\/div>\n<!--\/themify_builder_content-->","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"builder_content":"<h2 style=\"text-align: center;\">\u00a0<\/h2> <p>\u00a0<\/p>\n<p>[recent_products per_page=\"8\" columns=\"4\"]<\/p>","_links":{"self":[{"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/pages\/1357"}],"collection":[{"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/comments?post=1357"}],"version-history":[{"count":2,"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/pages\/1357\/revisions"}],"predecessor-version":[{"id":1389,"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/pages\/1357\/revisions\/1389"}],"wp:attachment":[{"href":"https:\/\/www.bis-sap.com\/nl\/wp-json\/wp\/v2\/media?parent=1357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}